{"id":8346,"date":"2023-08-30T10:01:02","date_gmt":"2023-08-30T10:01:02","guid":{"rendered":"https:\/\/cursadebombers.barcelona\/?p=8346"},"modified":"2023-08-30T10:17:50","modified_gmt":"2023-08-30T10:17:50","slug":"esta-es-la-camiseta-oficial-de-la-24a-edicion-de-la-vueling-carrera-de-bombers-de-barcelona","status":"publish","type":"post","link":"https:\/\/cursadebombers.barcelona\/es\/2023\/08\/30\/esta-es-la-camiseta-oficial-de-la-24a-edicion-de-la-vueling-carrera-de-bombers-de-barcelona\/","title":{"rendered":"Esta es la camiseta oficial de la 24\u00aa edici\u00f3n de la Vueling Carrera de Bombers de Barcelona"},"content":{"rendered":"<div class=\"et_d4_element et_pb_section et_pb_section_0  et_pb_css_mix_blend_mode et_section_regular et_block_section\" >\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_d4_element et_pb_row et_pb_row_0  et_pb_css_mix_blend_mode et_block_row\">\n\t\t\t\t<div class=\"et_d4_element et_pb_column_4_4 et_pb_column et_pb_column_0  et_pb_css_mix_blend_mode et-last-child et_block_column\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_0  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><h2 style=\"text-align: justify;\"><b>-El claim de esta edici\u00f3n hace referencia al lema de los bomberos de Barcelona: \u201cVetllem, protegim i salvem\u201d<\/b><\/h2>\n<h2 style=\"text-align: justify;\"><b>-El dise\u00f1o con los l\u00edneas horizontales representa a las del habitual uniforme de bomberos<\/b><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\"><br \/>Quedan pocos meses para disfrutar de la <\/span><b>10K m\u00e1s r\u00e1pida de Barcelona<\/b><span style=\"font-weight: 400;\">, que para su <\/span><b>24\u00aa edici\u00f3n<\/b><span style=\"font-weight: 400;\">, tiene preparada una jornada de deporte, m\u00fasica, solidaridad y muchas emociones para los miles de corredores.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">El <\/span><b>22 de octubre<\/b><span style=\"font-weight: 400;\"> volver\u00e1 la fiesta, y esta vez, con <\/span><b>nuevo circuito<\/b><span style=\"font-weight: 400;\">. Consistir\u00e1 en un recorrido <\/span><b>360\u00ba<\/b><span style=\"font-weight: 400;\"> con una curva menos del habitual, lo que la convertir\u00e1 en una carrera 10K <\/span><b>todav\u00eda m\u00e1s r\u00e1pida<\/b><span style=\"font-weight: 400;\">, ideal para que los veteranos superen su marca y los principiantes puedan acabarla sin problemas.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><\/div>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_video et_pb_video_0\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_video_box\"><iframe loading=\"lazy\" title=\"\ud83c\udfc3\u200d\u2642\ufe0f La samarreta de la Vueling Cursa Bombers Barcelona 2023 \ud83d\udc69\u200d\ud83d\ude92\" width=\"1080\" height=\"608\" src=\"https:\/\/www.youtube.com\/embed\/WykSC5aLKDw?feature=oembed\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n\t\t\t\t\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_1  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La Vueling Cursa de Bombers 2023 ha hecho sus deberes y ya tiene lista la<\/span><b> nueva camiseta <\/b><span style=\"font-weight: 400;\">para esta edici\u00f3n. Consiste en una camiseta amarilla con unas franjas horizontales muy sutiles, referenciando el habitual traje de bomberos del cuerpo de la ciudad. El claim elegido para esta edici\u00f3n tambi\u00e9n hace homenaje a los bomberos, y es <\/span><b>\u201cVetllem, protegim i salvem\u201d<\/b><span style=\"font-weight: 400;\">, que se localiza en el centro de la camiseta. Es posible que te suene, puesto que est\u00e1 inspirado en el lema de los bomberos de Barcelona, que es id\u00e9ntico a excepci\u00f3n de la \u00faltima palabra, modificada por <\/span><i><span style=\"font-weight: 400;\">salvamos<\/span><\/i><span style=\"font-weight: 400;\">, con el objetivo de hacer honor a los protagonistas de la carrera. El dise\u00f1o tambi\u00e9n est\u00e1 compuesto por un dibujo de un casco rojo de bomberos y logo de la carrera en la parte superior izquierda.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Recuerda que para conseguirla, solo te tienes que unirte al reto y correr con los bomberos. Esta se te brindar\u00e1 junto con los otros productos de la bolsa del corredor, que se recoger\u00e1 con antelaci\u00f3n en las tiendas Decathlon que se indiquen.\u00a0<\/span><span style=\"font-weight: 400;\"><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Si todav\u00eda no est\u00e1s apuntado o apuntada, puedes hacer-lo a trav\u00e9s de este bot\u00f3n:<\/span><\/p><\/div>\n\t\t\t<\/div><div class=\"et_pb_button_module_wrapper et_pb_button_0_wrapper et_pb_button_alignment_center et_pb_module \">\n\t\t\t\t<a class=\"et_pb_button et_d4_element et_pb_button_0 et_pb_bg_layout_light et_block_module\" href=\"https:\/\/xipgroc.cat\/es\/curses\/bombers2023\/10k\/inscripcio\/cursa%20\">Inscr\u00edbete aqu\u00ed<\/a>\n\t\t\t<\/div><div class=\"et_pb_module et_d4_element et_pb_text et_pb_text_2  et_pb_text_align_left et_pb_bg_layout_light\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"et_pb_text_inner\"><p><span style=\"font-weight: 400;\">No olvides revisar tu talla en este <\/span><a href=\"https:\/\/cursadebombers.barcelona\/es\/fira-del-corredor\/\"><span style=\"font-weight: 400;\">link<\/span><\/a><span style=\"font-weight: 400;\"> para seleccionar el correcto a la hora de realizar tu inscripci\u00f3n.<\/span><\/p><\/div>\n\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El claim de esta edici\u00f3n hace referencia al lema de los bomberos de Barcelona: \u201cVetllem, protegim i salvem\u201d y el dise\u00f1o con los l\u00edneas horizontales representa a las del habitual uniforme de bomberos<\/p>\n","protected":false},"author":4,"featured_media":8347,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<p><b>-El claim de esta edici\u00f3n hace referencia al lema de los bomberos de Barcelona: \u201cVetllem, protegim i salvem\u201d<\/b><\/p><p><b>- El dise\u00f1o con los l\u00edneas horizontales representa a las del habitual uniforme de bomberos<\/b><\/p><p><span style=\"font-weight: 400;\">Quedan pocos meses para disfrutar de la <\/span><b>10K m\u00e1s r\u00e1pida de Barcelona<\/b><span style=\"font-weight: 400;\">, que para su <\/span><b>24\u00aa edici\u00f3n<\/b><span style=\"font-weight: 400;\">, tiene preparada una jornada de deporte, m\u00fasica, solidaridad y muchas emociones para los miles de corredores.<\/span><\/p><p><span style=\"font-weight: 400;\">El <\/span><b>22 de octubre<\/b><span style=\"font-weight: 400;\"> volver\u00e1 la fiesta, y esta vez, con <\/span><b>nuevo circuito<\/b><span style=\"font-weight: 400;\">. Consistir\u00e1 en un recorrido <\/span><b>360\u00ba<\/b><span style=\"font-weight: 400;\"> con una curva menos del habitual, lo que la convertir\u00e1 en una carrera 10K <\/span><b>todav\u00eda m\u00e1s r\u00e1pida<\/b><span style=\"font-weight: 400;\">, ideal para que los veteranos superen su marca y los principiantes puedan acabarla sin problemas.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">La Vueling Cursa de Bombers 2023 ha hecho sus deberes y ya tiene lista la<\/span><b> nueva camiseta <\/b><span style=\"font-weight: 400;\">para esta edici\u00f3n. Consiste en una camiseta amarilla con unas franjas horizontales muy sutiles, referenciando el habitual traje de bomberos del cuerpo de la ciudad. El claim elegido para esta edici\u00f3n tambi\u00e9n hace homenaje a los bomberos, y es <\/span><b>\u201cVetllem, protegim i salvem\u201d<\/b><span style=\"font-weight: 400;\">, que se localiza en el centro de la camiseta. Es posible que te suene, puesto que est\u00e1 inspirado en el lema de los bomberos de Barcelona, que es id\u00e9ntico a excepci\u00f3n de la \u00faltima palabra, modificada por <\/span><i><span style=\"font-weight: 400;\">salvamos<\/span><\/i><span style=\"font-weight: 400;\">, con el objetivo de hacer honor a los protagonistas de la carrera. El dise\u00f1o tambi\u00e9n est\u00e1 compuesto por un dibujo de un casco rojo de bomberos y logo de la carrera en la parte superior izquierda.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Recuerda que para conseguirla, solo te tienes que unirte al reto y correr con los bomberos. Esta se te brindar\u00e1 junto con los otros productos de la bolsa del corredor, que se recoger\u00e1 con antelaci\u00f3n en las tiendas Decathlon que se indiquen.\u00a0<\/span><\/p>","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-8346","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Camiseta oficial de la 24\u00aa edici\u00f3n de la Vueling Carrera de Bombers de Barcelona<\/title>\n<meta name=\"description\" content=\"El claim de esta edici\u00f3n hace referencia al lema de los bomberos de Barcelona: \u201cVetllem, protegim i salvem\u201d y el dise\u00f1o con los l\u00edneas horizontales representa a las del habitual uniforme de bomberos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cursadebombers.barcelona\/es\/2023\/08\/30\/esta-es-la-camiseta-oficial-de-la-24a-edicion-de-la-vueling-carrera-de-bombers-de-barcelona\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Camiseta oficial de la 24\u00aa edici\u00f3n de la Vueling Carrera de Bombers de Barcelona\" \/>\n<meta property=\"og:description\" content=\"El claim de esta edici\u00f3n hace referencia al lema de los bomberos de Barcelona: \u201cVetllem, protegim i salvem\u201d y el dise\u00f1o con los l\u00edneas horizontales representa a las del habitual uniforme de bomberos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cursadebombers.barcelona\/es\/2023\/08\/30\/esta-es-la-camiseta-oficial-de-la-24a-edicion-de-la-vueling-carrera-de-bombers-de-barcelona\/\" \/>\n<meta property=\"og:site_name\" content=\"Cursa de Bombers\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CursadeBombers\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-30T10:01:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-30T10:17:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cursadebombers.barcelona\/wp-content\/uploads\/2023\/08\/Image_20230828_152430-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1890\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Toni\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cursadebombers\" \/>\n<meta name=\"twitter:site\" content=\"@cursadebombers\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Toni\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cursadebombers.barcelona\\\/es\\\/2023\\\/08\\\/30\\\/esta-es-la-camiseta-oficial-de-la-24a-edicion-de-la-vueling-carrera-de-bombers-de-barcelona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cursadebombers.barcelona\\\/es\\\/2023\\\/08\\\/30\\\/esta-es-la-camiseta-oficial-de-la-24a-edicion-de-la-vueling-carrera-de-bombers-de-barcelona\\\/\"},\"author\":{\"name\":\"Toni\",\"@id\":\"https:\\\/\\\/cursadebombers.barcelona\\\/#\\\/schema\\\/person\\\/35d4ce676dd5e5d74d5c815d7644a99a\"},\"headline\":\"Esta es la camiseta oficial de la 24\u00aa edici\u00f3n de la Vueling Carrera de Bombers de Barcelona\",\"datePublished\":\"2023-08-30T10:01:02+00:00\",\"dateModified\":\"2023-08-30T10:17:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cursadebombers.barcelona\\\/es\\\/2023\\\/08\\\/30\\\/esta-es-la-camiseta-oficial-de-la-24a-edicion-de-la-vueling-carrera-de-bombers-de-barcelona\\\/\"},\"wordCount\":513,\"publisher\":{\"@id\":\"https:\\\/\\\/cursadebombers.barcelona\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cursadebombers.barcelona\\\/es\\\/2023\\\/08\\\/30\\\/esta-es-la-camiseta-oficial-de-la-24a-edicion-de-la-vueling-carrera-de-bombers-de-barcelona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cursadebombers.barcelona\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Image_20230828_152430-scaled.jpeg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cursadebombers.barcelona\\\/es\\\/2023\\\/08\\\/30\\\/esta-es-la-camiseta-oficial-de-la-24a-edicion-de-la-vueling-carrera-de-bombers-de-barcelona\\\/\",\"url\":\"https:\\\/\\\/cursadebombers.barcelona\\\/es\\\/2023\\\/08\\\/30\\\/esta-es-la-camiseta-oficial-de-la-24a-edicion-de-la-vueling-carrera-de-bombers-de-barcelona\\\/\",\"name\":\"Camiseta oficial de la 24\u00aa edici\u00f3n de la Vueling Carrera de Bombers de Barcelona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cursadebombers.barcelona\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cursadebombers.barcelona\\\/es\\\/2023\\\/08\\\/30\\\/esta-es-la-camiseta-oficial-de-la-24a-edicion-de-la-vueling-carrera-de-bombers-de-barcelona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cursadebombers.barcelona\\\/es\\\/2023\\\/08\\\/30\\\/esta-es-la-camiseta-oficial-de-la-24a-edicion-de-la-vueling-carrera-de-bombers-de-barcelona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cursadebombers.barcelona\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Image_20230828_152430-scaled.jpeg\",\"datePublished\":\"2023-08-30T10:01:02+00:00\",\"dateModified\":\"2023-08-30T10:17:50+00:00\",\"description\":\"El claim de esta edici\u00f3n hace referencia al lema de los bomberos de Barcelona: \u201cVetllem, protegim i salvem\u201d y el dise\u00f1o con los l\u00edneas horizontales representa a las del habitual uniforme de bomberos\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cursadebombers.barcelona\\\/es\\\/2023\\\/08\\\/30\\\/esta-es-la-camiseta-oficial-de-la-24a-edicion-de-la-vueling-carrera-de-bombers-de-barcelona\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cursadebombers.barcelona\\\/es\\\/2023\\\/08\\\/30\\\/esta-es-la-camiseta-oficial-de-la-24a-edicion-de-la-vueling-carrera-de-bombers-de-barcelona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cursadebombers.barcelona\\\/es\\\/2023\\\/08\\\/30\\\/esta-es-la-camiseta-oficial-de-la-24a-edicion-de-la-vueling-carrera-de-bombers-de-barcelona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cursadebombers.barcelona\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Image_20230828_152430-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/cursadebombers.barcelona\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Image_20230828_152430-scaled.jpeg\",\"width\":2560,\"height\":1890},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cursadebombers.barcelona\\\/es\\\/2023\\\/08\\\/30\\\/esta-es-la-camiseta-oficial-de-la-24a-edicion-de-la-vueling-carrera-de-bombers-de-barcelona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/cursadebombers.barcelona\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esta es la camiseta oficial de la 24\u00aa edici\u00f3n de la Vueling Carrera de Bombers de Barcelona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cursadebombers.barcelona\\\/#website\",\"url\":\"https:\\\/\\\/cursadebombers.barcelona\\\/\",\"name\":\"Cursa de Bombers\",\"description\":\"La Cursa dels Bombers de Barcelona.\",\"publisher\":{\"@id\":\"https:\\\/\\\/cursadebombers.barcelona\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cursadebombers.barcelona\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cursadebombers.barcelona\\\/#organization\",\"name\":\"Cursa de Bombers\",\"url\":\"https:\\\/\\\/cursadebombers.barcelona\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cursadebombers.barcelona\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cursadebombers.barcelona\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-cursa-bombers-app.png\",\"contentUrl\":\"https:\\\/\\\/cursadebombers.barcelona\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-cursa-bombers-app.png\",\"width\":512,\"height\":512,\"caption\":\"Cursa de Bombers\"},\"image\":{\"@id\":\"https:\\\/\\\/cursadebombers.barcelona\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CursadeBombers\\\/\",\"https:\\\/\\\/x.com\\\/cursadebombers\",\"https:\\\/\\\/www.instagram.com\\\/cursadebombers\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cursadebombers.barcelona\\\/#\\\/schema\\\/person\\\/35d4ce676dd5e5d74d5c815d7644a99a\",\"name\":\"Toni\",\"url\":\"https:\\\/\\\/cursadebombers.barcelona\\\/es\\\/author\\\/toni\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Camiseta oficial de la 24\u00aa edici\u00f3n de la Vueling Carrera de Bombers de Barcelona","description":"El claim de esta edici\u00f3n hace referencia al lema de los bomberos de Barcelona: \u201cVetllem, protegim i salvem\u201d y el dise\u00f1o con los l\u00edneas horizontales representa a las del habitual uniforme de bomberos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cursadebombers.barcelona\/es\/2023\/08\/30\/esta-es-la-camiseta-oficial-de-la-24a-edicion-de-la-vueling-carrera-de-bombers-de-barcelona\/","og_locale":"es_ES","og_type":"article","og_title":"Camiseta oficial de la 24\u00aa edici\u00f3n de la Vueling Carrera de Bombers de Barcelona","og_description":"El claim de esta edici\u00f3n hace referencia al lema de los bomberos de Barcelona: \u201cVetllem, protegim i salvem\u201d y el dise\u00f1o con los l\u00edneas horizontales representa a las del habitual uniforme de bomberos","og_url":"https:\/\/cursadebombers.barcelona\/es\/2023\/08\/30\/esta-es-la-camiseta-oficial-de-la-24a-edicion-de-la-vueling-carrera-de-bombers-de-barcelona\/","og_site_name":"Cursa de Bombers","article_publisher":"https:\/\/www.facebook.com\/CursadeBombers\/","article_published_time":"2023-08-30T10:01:02+00:00","article_modified_time":"2023-08-30T10:17:50+00:00","og_image":[{"width":2560,"height":1890,"url":"https:\/\/cursadebombers.barcelona\/wp-content\/uploads\/2023\/08\/Image_20230828_152430-scaled.jpeg","type":"image\/jpeg"}],"author":"Toni","twitter_card":"summary_large_image","twitter_creator":"@cursadebombers","twitter_site":"@cursadebombers","twitter_misc":{"Escrito por":"Toni"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cursadebombers.barcelona\/es\/2023\/08\/30\/esta-es-la-camiseta-oficial-de-la-24a-edicion-de-la-vueling-carrera-de-bombers-de-barcelona\/#article","isPartOf":{"@id":"https:\/\/cursadebombers.barcelona\/es\/2023\/08\/30\/esta-es-la-camiseta-oficial-de-la-24a-edicion-de-la-vueling-carrera-de-bombers-de-barcelona\/"},"author":{"name":"Toni","@id":"https:\/\/cursadebombers.barcelona\/#\/schema\/person\/35d4ce676dd5e5d74d5c815d7644a99a"},"headline":"Esta es la camiseta oficial de la 24\u00aa edici\u00f3n de la Vueling Carrera de Bombers de Barcelona","datePublished":"2023-08-30T10:01:02+00:00","dateModified":"2023-08-30T10:17:50+00:00","mainEntityOfPage":{"@id":"https:\/\/cursadebombers.barcelona\/es\/2023\/08\/30\/esta-es-la-camiseta-oficial-de-la-24a-edicion-de-la-vueling-carrera-de-bombers-de-barcelona\/"},"wordCount":513,"publisher":{"@id":"https:\/\/cursadebombers.barcelona\/#organization"},"image":{"@id":"https:\/\/cursadebombers.barcelona\/es\/2023\/08\/30\/esta-es-la-camiseta-oficial-de-la-24a-edicion-de-la-vueling-carrera-de-bombers-de-barcelona\/#primaryimage"},"thumbnailUrl":"https:\/\/cursadebombers.barcelona\/wp-content\/uploads\/2023\/08\/Image_20230828_152430-scaled.jpeg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cursadebombers.barcelona\/es\/2023\/08\/30\/esta-es-la-camiseta-oficial-de-la-24a-edicion-de-la-vueling-carrera-de-bombers-de-barcelona\/","url":"https:\/\/cursadebombers.barcelona\/es\/2023\/08\/30\/esta-es-la-camiseta-oficial-de-la-24a-edicion-de-la-vueling-carrera-de-bombers-de-barcelona\/","name":"Camiseta oficial de la 24\u00aa edici\u00f3n de la Vueling Carrera de Bombers de Barcelona","isPartOf":{"@id":"https:\/\/cursadebombers.barcelona\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cursadebombers.barcelona\/es\/2023\/08\/30\/esta-es-la-camiseta-oficial-de-la-24a-edicion-de-la-vueling-carrera-de-bombers-de-barcelona\/#primaryimage"},"image":{"@id":"https:\/\/cursadebombers.barcelona\/es\/2023\/08\/30\/esta-es-la-camiseta-oficial-de-la-24a-edicion-de-la-vueling-carrera-de-bombers-de-barcelona\/#primaryimage"},"thumbnailUrl":"https:\/\/cursadebombers.barcelona\/wp-content\/uploads\/2023\/08\/Image_20230828_152430-scaled.jpeg","datePublished":"2023-08-30T10:01:02+00:00","dateModified":"2023-08-30T10:17:50+00:00","description":"El claim de esta edici\u00f3n hace referencia al lema de los bomberos de Barcelona: \u201cVetllem, protegim i salvem\u201d y el dise\u00f1o con los l\u00edneas horizontales representa a las del habitual uniforme de bomberos","breadcrumb":{"@id":"https:\/\/cursadebombers.barcelona\/es\/2023\/08\/30\/esta-es-la-camiseta-oficial-de-la-24a-edicion-de-la-vueling-carrera-de-bombers-de-barcelona\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cursadebombers.barcelona\/es\/2023\/08\/30\/esta-es-la-camiseta-oficial-de-la-24a-edicion-de-la-vueling-carrera-de-bombers-de-barcelona\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cursadebombers.barcelona\/es\/2023\/08\/30\/esta-es-la-camiseta-oficial-de-la-24a-edicion-de-la-vueling-carrera-de-bombers-de-barcelona\/#primaryimage","url":"https:\/\/cursadebombers.barcelona\/wp-content\/uploads\/2023\/08\/Image_20230828_152430-scaled.jpeg","contentUrl":"https:\/\/cursadebombers.barcelona\/wp-content\/uploads\/2023\/08\/Image_20230828_152430-scaled.jpeg","width":2560,"height":1890},{"@type":"BreadcrumbList","@id":"https:\/\/cursadebombers.barcelona\/es\/2023\/08\/30\/esta-es-la-camiseta-oficial-de-la-24a-edicion-de-la-vueling-carrera-de-bombers-de-barcelona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/cursadebombers.barcelona\/es\/"},{"@type":"ListItem","position":2,"name":"Esta es la camiseta oficial de la 24\u00aa edici\u00f3n de la Vueling Carrera de Bombers de Barcelona"}]},{"@type":"WebSite","@id":"https:\/\/cursadebombers.barcelona\/#website","url":"https:\/\/cursadebombers.barcelona\/","name":"Cursa de Bombers","description":"La Cursa dels Bombers de Barcelona.","publisher":{"@id":"https:\/\/cursadebombers.barcelona\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cursadebombers.barcelona\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cursadebombers.barcelona\/#organization","name":"Cursa de Bombers","url":"https:\/\/cursadebombers.barcelona\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cursadebombers.barcelona\/#\/schema\/logo\/image\/","url":"https:\/\/cursadebombers.barcelona\/wp-content\/uploads\/2025\/06\/logo-cursa-bombers-app.png","contentUrl":"https:\/\/cursadebombers.barcelona\/wp-content\/uploads\/2025\/06\/logo-cursa-bombers-app.png","width":512,"height":512,"caption":"Cursa de Bombers"},"image":{"@id":"https:\/\/cursadebombers.barcelona\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CursadeBombers\/","https:\/\/x.com\/cursadebombers","https:\/\/www.instagram.com\/cursadebombers\/"]},{"@type":"Person","@id":"https:\/\/cursadebombers.barcelona\/#\/schema\/person\/35d4ce676dd5e5d74d5c815d7644a99a","name":"Toni","url":"https:\/\/cursadebombers.barcelona\/es\/author\/toni\/"}]}},"_links":{"self":[{"href":"https:\/\/cursadebombers.barcelona\/es\/wp-json\/wp\/v2\/posts\/8346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cursadebombers.barcelona\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cursadebombers.barcelona\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cursadebombers.barcelona\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/cursadebombers.barcelona\/es\/wp-json\/wp\/v2\/comments?post=8346"}],"version-history":[{"count":5,"href":"https:\/\/cursadebombers.barcelona\/es\/wp-json\/wp\/v2\/posts\/8346\/revisions"}],"predecessor-version":[{"id":8386,"href":"https:\/\/cursadebombers.barcelona\/es\/wp-json\/wp\/v2\/posts\/8346\/revisions\/8386"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cursadebombers.barcelona\/es\/wp-json\/wp\/v2\/media\/8347"}],"wp:attachment":[{"href":"https:\/\/cursadebombers.barcelona\/es\/wp-json\/wp\/v2\/media?parent=8346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cursadebombers.barcelona\/es\/wp-json\/wp\/v2\/categories?post=8346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cursadebombers.barcelona\/es\/wp-json\/wp\/v2\/tags?post=8346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}